{"id":13723,"date":"2020-10-01T00:19:50","date_gmt":"2020-10-01T03:19:50","guid":{"rendered":"https:\/\/comunique-se.com.br\/blog\/?p=13723"},"modified":"2020-10-30T18:36:01","modified_gmt":"2020-10-30T21:36:01","slug":"como-o-comunique-se-360-pode-potencializar-a-comunicacao-dos-orgaos-publicos","status":"publish","type":"post","link":"https:\/\/comunique-se.com.br\/blog\/como-o-comunique-se-360-pode-potencializar-a-comunicacao-dos-orgaos-publicos\/","title":{"rendered":"Como o Comunique-se 360 pode potencializar a comunica\u00e7\u00e3o dos \u00f3rg\u00e3os p\u00fablicos"},"content":{"rendered":"\r\n<p>O Comunique-se 360 \u00e9 a <a href=\"https:\/\/comunique-se.com.br\/blog\/cse360\/\" target=\"_blank\" rel=\"noreferrer noopener\">nova plataforma de comunica\u00e7\u00e3o <\/a>e marketing do Grupo Comunique-se. Com uma abordagem projetada para multip\u00fablicos, a solu\u00e7\u00e3o se prop\u00f5e a conectar marcas aos seus stakeholders. O software pode ser utilizado por in\u00fameros setores no mercado, assim como os \u00f3rg\u00e3os p\u00fablicos.\u00a0<\/p>\r\n\r\n\r\n\r\n<p>Nesse setor, \u00e9 papel da comunica\u00e7\u00e3o criar uma canal de aproxima\u00e7\u00e3o entre o \u00f3rg\u00e3o p\u00fablico a sociedade, a fim de prestar servi\u00e7o e levar informa\u00e7\u00e3o \u00e0s pessoas. Al\u00e9m de estabelecer e produzir as principais estrat\u00e9gias de comunica\u00e7\u00e3o no \u00e2mbito geral.\u00a0<\/p>\r\n\r\n\r\n\r\n<p>Dentro desse processo, a responsabilidade de garantir a liga\u00e7\u00e3o entre entidades e seus multip\u00fablico \u00e9 da assessoria de comunica\u00e7\u00e3o, popularmente chamada de ASCOM \u2014 que engloba atividades relacionadas a assessoria de imprensa, publicidade e rela\u00e7\u00f5es p\u00fablicas.\u00a0<\/p>\r\n\r\n\r\n\r\n<p>Abaixo, vamos abordar com a plataforma <strong>Comunique-se 360 <\/strong>pode contribuir diretamente para uma comunica\u00e7\u00e3o com todos os p\u00fablicos de interesse de um \u00f3rg\u00e3o p\u00fablico.\u00a0<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\"><strong>Funcionalidades do Comunique-se 360 para \u00f3rg\u00e3o p\u00fablico<\/strong><\/h3>\r\n\r\n\r\n\r\n<h4 class=\"wp-block-heading\"><strong>#1 Relacionamento com a imprensa\u00a0<\/strong><\/h4>\r\n\r\n\r\n\r\n<p>Os jornalistas s\u00e3o, sem d\u00favidas, um dos p\u00fablicos que mais exigem um amplo relacionamento por parte dos \u00f3rg\u00e3os. Logo, o trabalho de assessoria de imprensa \u00e9 indispens\u00e1vel \u2014 tanto para envios de <em>releases<\/em> com os principais comunicados quanto para o pr\u00f3prio atendimento aos jornalistas.\u00a0<\/p>\r\n\r\n\r\n\r\n<p>Para que tal rela\u00e7\u00e3o com a imprensa gere bons retornos para o \u00f3rg\u00e3o p\u00fablico, torna-se primordial que o profissional respons\u00e1vel pela ASCOM tenha em m\u00e3os um bom mailing de jornalistas, com contatos estrat\u00e9gicos.\u00a0<\/p>\r\n\r\n\r\n\r\n<p>Geralmente, os comunicados enviados aos jornalistas bem segmentados, seja por regi\u00e3o ou propriamente por tipos de assuntos. Na pr\u00e1tica, \u00e9 necess\u00e1rio ter os contatos dos colegas de reda\u00e7\u00e3o para facilitar as tarefas di\u00e1rias do \u00f3rg\u00e3o e garantir que os releases sejam entregues aos profissionais corretos.\u00a0<\/p>\r\n\r\n\r\n\r\n<p>No Comunique-se 360, voc\u00ea tem acesso ao maior banco de dados de jornalistas. Com mais de 60 mil contatos dispon\u00edveis na plataforma, \u00e9 poss\u00edvel encontrar o perfil ideal de profissionais para distribuir sugest\u00f5es de pautas e ampliar o relacionamento.\u00a0<\/p>\r\n\r\n\r\n\r\n<h4 class=\"wp-block-heading\"><strong>Contatos com garantia de atualiza\u00e7\u00e3o<\/strong><\/h4>\r\n\r\n\r\n\r\n<p>Com a alta taxa de rotatividade nas reda\u00e7\u00f5es, naturalmente, ao executar o trabalho de assessoria de imprensa \u00e9 comum que com o tempo alguns contatos fiquem desatualizados. Seja porque o jornalista trocou de ve\u00edculo ou apenas mudou sua cobertura\u00a0 \u2014 editoria.\u00a0<\/p>\r\n\r\n\r\n\r\n<p>Atualizar um mailing list na \u201cunha\u201d n\u00e3o \u00e9 tarefa simples. Exige muito tempo e h\u00e1 pouca margem para erro. Para evitar qualquer imprevisto com desatualiza\u00e7\u00e3o de dados, o Comunique-se 360 garante uma taxa em contrato, a fim de garantir que seus releases cheguem aos destinat\u00e1rios desejados.<\/p>\r\n\r\n\r\n\r\n<h4 class=\"wp-block-heading\"><strong>Hist\u00f3rico de relacionamento<\/strong>\u00a0<\/h4>\r\n\r\n\r\n\r\n<p>Para facilitar o trabalho da assessoria de imprensa, o Comunique-se tem ainda, uma esp\u00e9cie de r\u00e9gua de relacionamento. \u00c9 poss\u00edvel, por exemplo, acessar o hist\u00f3rico de contatos com cada um dos jornalistas. Logo, h\u00e1 como deixar tudo registrado.\u00a0<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"746\" class=\"wp-image-13724\" src=\"https:\/\/comunique-se.com.br\/blog\/wp-content\/uploads\/2020\/09\/Screen-Shot-2020-07-21-at-15.28.47-1024x746.png\" alt=\"\" srcset=\"https:\/\/comunique-se.com.br\/blog\/wp-content\/uploads\/2020\/09\/Screen-Shot-2020-07-21-at-15.28.47-1024x746.png 1024w, https:\/\/comunique-se.com.br\/blog\/wp-content\/uploads\/2020\/09\/Screen-Shot-2020-07-21-at-15.28.47-300x219.png 300w, https:\/\/comunique-se.com.br\/blog\/wp-content\/uploads\/2020\/09\/Screen-Shot-2020-07-21-at-15.28.47-768x560.png 768w, https:\/\/comunique-se.com.br\/blog\/wp-content\/uploads\/2020\/09\/Screen-Shot-2020-07-21-at-15.28.47.png 1357w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\r\n\r\n\r\n\r\n<p>A funcionalidade contribui diretamente para o trabalho em equipe, onde mais de uma pessoa utilize a plataforma para executar as a\u00e7\u00f5es. E com o tempo, h\u00e1 como analisar os jornalistas que mais interagem com seus comunicados, basta recorrer \u00e0s m\u00e9tricas dispon\u00edveis de forma individual.\u00a0<\/p>\r\n\r\n\r\n\r\n<h4 class=\"wp-block-heading\"><strong>Mailing Vip<\/strong><\/h4>\r\n\r\n\r\n\r\n<p>No ramo de assessoria de imprensa \u00e9 comum que os profissionais que se relacionam com os jornalistas de reda\u00e7\u00e3o tenha seus pr\u00f3prios contatos \u2014 o que \u00e9 popularmente conhecido no setor como mailing vip.\u00a0<\/p>\r\n\r\n\r\n\r\n<p>\u00c9 natural que, com o networking, um assessor tenha o n\u00famero direto de um ou outro jornalista. E para ter tudo registrado tamb\u00e9m com sua lista vip, \u00e9 poss\u00edvel fazer upload da planilha no Comunique-360.\u00a0<\/p>\r\n\r\n\r\n\r\n<p>Assim, voc\u00ea pode usufruir das principais funcionalidades da plataforma para sua pr\u00f3pria lista. Vale ressaltar que, qualquer lista importada, o acesso aos dados \u00e9 exclusivamente do propriet\u00e1rio. Afinal, sabemos que em uma estrat\u00e9gia de comunica\u00e7\u00e3o, tais listas s\u00e3o extremamente pertinentes e geram grandes resultados.\u00a0<\/p>\r\n\r\n\r\n\r\n<h4 class=\"wp-block-heading\"><strong>#2 Monitore not\u00edcias em todos os tipos de m\u00eddia\u00a0<\/strong><\/h4>\r\n\r\n\r\n\r\n<p>Dentro do trabalho de assessoria da comunica\u00e7\u00e3o, mensurar todas as principais not\u00edcias que tenha rela\u00e7\u00e3o com o \u00f3rg\u00e3o p\u00fablico na m\u00eddia \u00e9 primordial. Com acesso \u00e0 informa\u00e7\u00e3o, \u00e9 poss\u00edvel fazer gest\u00e3o de crise e mensurar os resultados.\u00a0<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"746\" class=\"wp-image-13725\" src=\"https:\/\/comunique-se.com.br\/blog\/wp-content\/uploads\/2020\/09\/Screen-Shot-2020-07-21-at-15.32.38-1024x746.png\" alt=\"\" srcset=\"https:\/\/comunique-se.com.br\/blog\/wp-content\/uploads\/2020\/09\/Screen-Shot-2020-07-21-at-15.32.38-1024x746.png 1024w, https:\/\/comunique-se.com.br\/blog\/wp-content\/uploads\/2020\/09\/Screen-Shot-2020-07-21-at-15.32.38-300x219.png 300w, https:\/\/comunique-se.com.br\/blog\/wp-content\/uploads\/2020\/09\/Screen-Shot-2020-07-21-at-15.32.38-768x560.png 768w, https:\/\/comunique-se.com.br\/blog\/wp-content\/uploads\/2020\/09\/Screen-Shot-2020-07-21-at-15.32.38.png 1357w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\r\n\r\n\r\n\r\n<p>Com o Comunique-se 360, h\u00e1 como monitorar not\u00edcias no Brasil e no mundo, nos principais ve\u00edculos de comunica\u00e7\u00e3o em todos os tipos de m\u00eddia: r\u00e1dio, TV, impresso e online. Basta listar as principais palavras-chave e express\u00f5es para ter em m\u00e3os todas as not\u00edcias veiculadas.\u00a0<\/p>\r\n\r\n\r\n\r\n<h4 class=\"wp-block-heading\"><strong>Clipagem retroativa<\/strong>\u00a0<\/h4>\r\n\r\n\r\n\r\n<p>Geralmente, a equipe de comunica\u00e7\u00e3o do \u00f3rg\u00e3o p\u00fablico altera com o tempo. Por isso, \u00e9 primordial contar com uma ferramenta que fa\u00e7a \u2018clipagem\u2019 retroativa, para capturar conte\u00fados antigos \u2014 quando a gest\u00e3o do setor ASCOM estava sob comando de outras pessoas \u2014 caso surja a necessidade de analisar algum conte\u00fado que j\u00e1 foi veiculado em outro per\u00edodo.\u00a0<\/p>\r\n\r\n\r\n\r\n<h4 class=\"wp-block-heading\"><strong>Alertas e relat\u00f3rios\u00a0<\/strong><\/h4>\r\n\r\n\r\n\r\n<p>Configure os alertas na plataforma para receber as notifica\u00e7\u00f5es em primeira m\u00e3o sempre que uma mat\u00e9ria for \u2018clipada\u2019. Para compartilhar as not\u00edcias, basta recorrer aos relat\u00f3rios autom\u00e1ticos. Em poucos cliques, \u00e9 poss\u00edvel enviar o conte\u00fado armazenado com a identidade visual da entidade, seja para o p\u00fablico interno ou externo.\u00a0<\/p>\r\n\r\n\r\n\r\n<h4 class=\"wp-block-heading\"><strong>#3 Construa e envie e-mails em poucos cliques\u00a0<\/strong><\/h4>\r\n\r\n\r\n\r\n<p>Em um \u00f3rg\u00e3o p\u00fablico \u00e9 primordial contar com uma plataforma de envios. Seja para enviar releases, newsletters e at\u00e9 mesmo e-mail marketing. No Comunique-se 360, voc\u00ea conta com um sistema profissional de constru\u00e7\u00e3o envios. Em poucos cliques, construa com as pr\u00f3prias m\u00e3os templates profissionais para maximizar os resultados de seus comunicados. Com a tecnologia \u2018<a href=\"https:\/\/pt.wikipedia.org\/wiki\/Drag-and-drop\" target=\"_blank\" rel=\"noreferrer noopener\" data-type=\"URL\" data-id=\"https:\/\/pt.wikipedia.org\/wiki\/Drag-and-drop\">Drag-and-drop<\/a>\u2019, basta selecionar os principais elementos para criar um e-mail extremamente atrativo.<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"470\" class=\"wp-image-13727\" src=\"https:\/\/comunique-se.com.br\/blog\/wp-content\/uploads\/2020\/09\/E-mails-envios-1024x470.png\" alt=\"\" srcset=\"https:\/\/comunique-se.com.br\/blog\/wp-content\/uploads\/2020\/09\/E-mails-envios-1024x470.png 1024w, https:\/\/comunique-se.com.br\/blog\/wp-content\/uploads\/2020\/09\/E-mails-envios-300x138.png 300w, https:\/\/comunique-se.com.br\/blog\/wp-content\/uploads\/2020\/09\/E-mails-envios-768x352.png 768w, https:\/\/comunique-se.com.br\/blog\/wp-content\/uploads\/2020\/09\/E-mails-envios.png 1350w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\r\n\r\n\r\n\r\n<h4 class=\"wp-block-heading\"><strong>Relat\u00f3rios completos\u00a0<\/strong><\/h4>\r\n\r\n\r\n\r\n<p>Ao finalizar cada campanha, automaticamente voc\u00ea acompanha pela tela em tempo real as principais m\u00e9tricas de seus envios. Tenha acesso \u00e0s taxas de abertura, de cliques, de cliques por abertura e, ainda, do pico de abertura. Fa\u00e7a testes A\/B para ampliar seus resultados com base em dados.\u00a0<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"836\" height=\"486\" class=\"wp-image-13728\" src=\"https:\/\/comunique-se.com.br\/blog\/wp-content\/uploads\/2020\/09\/relatorio_e-mail_mkt.png\" alt=\"\" srcset=\"https:\/\/comunique-se.com.br\/blog\/wp-content\/uploads\/2020\/09\/relatorio_e-mail_mkt.png 836w, https:\/\/comunique-se.com.br\/blog\/wp-content\/uploads\/2020\/09\/relatorio_e-mail_mkt-300x174.png 300w, https:\/\/comunique-se.com.br\/blog\/wp-content\/uploads\/2020\/09\/relatorio_e-mail_mkt-768x446.png 768w\" sizes=\"auto, (max-width: 836px) 100vw, 836px\" \/><\/figure>\r\n\r\n\r\n\r\n<p>Com o tempo, tenha controle sobre suas taxas m\u00e9dias para cada p\u00fablico. Compare com as m\u00e9dias de mercado e encontre t\u00e9cnicas para potencializar os resultados. Tenha controle sobre quem abriu ou n\u00e3o seu e-mail \u2014 para facilitar e personalizar o follow up.\u00a0<\/p>\r\n\r\n\r\n\r\n<h4 class=\"wp-block-heading\"><strong>Concluindo\u2026\u00a0<\/strong><\/h4>\r\n\r\n\r\n\r\n<p>O Comunique-se 360 \u00e9 primordial para uma comunica\u00e7\u00e3o completa em um \u00f3rg\u00e3o p\u00fablico. Tenha todas as ferramentas ess\u00eancias em uma \u00fanica plataforma. Otimize tempo com as integra\u00e7\u00f5es e reduza os custos com in\u00fameros fornecedores. Maximize e potencialize os resultados com o software completo de comunica\u00e7\u00e3o e marketing.\u00a0<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>O Comunique-se 360 \u00e9 a nova plataforma de comunica\u00e7\u00e3o e marketing do Grupo Comunique-se. Com uma abordagem projetada para multip\u00fablicos, a solu\u00e7\u00e3o se prop\u00f5e a conectar marcas aos seus stakeholders. O software pode ser utilizado por in\u00fameros setores no mercado, assim como os \u00f3rg\u00e3os p\u00fablicos.\u00a0 Nesse setor, \u00e9 papel da comunica\u00e7\u00e3o criar uma canal de&hellip;<\/p>\n","protected":false},"author":20,"featured_media":13730,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[5],"tags":[],"yst_prominent_words":[],"class_list":["post-13723","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicacao-corporativa","category-5","description-off"],"_links":{"self":[{"href":"https:\/\/comunique-se.com.br\/blog\/wp-json\/wp\/v2\/posts\/13723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunique-se.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunique-se.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunique-se.com.br\/blog\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/comunique-se.com.br\/blog\/wp-json\/wp\/v2\/comments?post=13723"}],"version-history":[{"count":0,"href":"https:\/\/comunique-se.com.br\/blog\/wp-json\/wp\/v2\/posts\/13723\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunique-se.com.br\/blog\/wp-json\/wp\/v2\/media\/13730"}],"wp:attachment":[{"href":"https:\/\/comunique-se.com.br\/blog\/wp-json\/wp\/v2\/media?parent=13723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunique-se.com.br\/blog\/wp-json\/wp\/v2\/categories?post=13723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunique-se.com.br\/blog\/wp-json\/wp\/v2\/tags?post=13723"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/comunique-se.com.br\/blog\/wp-json\/wp\/v2\/yst_prominent_words?post=13723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}